{"id":1035,"date":"2023-02-06T10:26:06","date_gmt":"2023-02-06T03:26:06","guid":{"rendered":"https:\/\/construction-1.matbao.website\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5.jpg"},"modified":"2023-02-06T10:26:06","modified_gmt":"2023-02-06T03:26:06","slug":"z4008728037271_acfe76c611213ef1073cb12fd62555a5-2","status":"inherit","type":"attachment","link":"https:\/\/bmglandscapecom742.mbws.vn\/en\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-2\/","title":{"rendered":"z4008728037271_acfe76c611213ef1073cb12fd62555a5"},"author":2,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-300x225.jpg 300w, https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-1024x768.jpg 1024w, https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-768x576.jpg 768w, https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":960,"file":"2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5.jpg","filesize":489520,"sizes":{"medium":{"file":"z4008728037271_acfe76c611213ef1073cb12fd62555a5-300x225.jpg","width":300,"height":225,"filesize":19065,"mime_type":"image\/jpeg","source_url":"https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-300x225.jpg"},"large":{"file":"z4008728037271_acfe76c611213ef1073cb12fd62555a5-1024x768.jpg","width":1024,"height":768,"filesize":188956,"mime_type":"image\/jpeg","source_url":"https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-1024x768.jpg"},"thumbnail":{"file":"z4008728037271_acfe76c611213ef1073cb12fd62555a5-150x150.jpg","width":150,"height":150,"filesize":7134,"mime_type":"image\/jpeg","source_url":"https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-150x150.jpg"},"medium_large":{"file":"z4008728037271_acfe76c611213ef1073cb12fd62555a5-768x576.jpg","width":768,"height":576,"filesize":110524,"mime_type":"image\/jpeg","source_url":"https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5-768x576.jpg"},"full":{"file":"z4008728037271_acfe76c611213ef1073cb12fd62555a5.jpg","width":1280,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/bmglandscapecom742.mbws.vn\/wp-content\/uploads\/2022\/11\/z4008728037271_acfe76c611213ef1073cb12fd62555a5.jpg","_links":{"self":[{"href":"https:\/\/bmglandscapecom742.mbws.vn\/en\/wp-json\/wp\/v2\/media\/1035"}],"collection":[{"href":"https:\/\/bmglandscapecom742.mbws.vn\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bmglandscapecom742.mbws.vn\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bmglandscapecom742.mbws.vn\/en\/wp-json\/wp\/v2\/users\/2"}]}}